{"id":31117,"date":"2025-11-06T13:53:07","date_gmt":"2025-11-06T12:53:07","guid":{"rendered":"https:\/\/animalproducts.nl\/product\/channel-slalom\/"},"modified":"2025-11-06T13:53:07","modified_gmt":"2025-11-06T12:53:07","slug":"channel-slalom","status":"publish","type":"product","link":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/","title":{"rendered":"Channel Slalom"},"content":{"rendered":"<p>Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.  <\/p>\n<p><strong>Produktmerkmale:<\/strong><\/p>\n<ul>\n<li>Robustes Material: Gefertigt aus langlebigen, stabilen Materialien f\u00fcr maximale Sicherheit und Standfestigkeit.<\/li>\n<li>Langlebig: Materialien, die dem Dauergebrauch standhalten.<\/li>\n<li>Basis: 3 Teile<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.  <\/p>\n","protected":false},"featured_media":29717,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[140,144,150,157],"product_tag":[],"class_list":{"0":"post-31117","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-beweglichkeit","7":"product_cat-beweglichkeitstraining","8":"product_cat-galican","9":"product_cat-slaloms","11":"first","12":"onbackorder","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Channel Slalom - Animal Products<\/title>\n<meta name=\"description\" content=\"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Channel Slalom - Animal Products\" \/>\n<meta property=\"og:description\" content=\"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/\" \/>\n<meta property=\"og:site_name\" content=\"Animal Products\" \/>\n<meta property=\"og:image\" content=\"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/11\/Slalom-Pasillo-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1711\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/\",\"url\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/\",\"name\":\"Channel Slalom - Animal Products\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/animalproducts.nl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Slalom-Pasillo-scaled.png\",\"datePublished\":\"2025-11-06T12:53:07+00:00\",\"description\":\"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/animalproducts.nl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Slalom-Pasillo-scaled.png\",\"contentUrl\":\"https:\\\/\\\/animalproducts.nl\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Slalom-Pasillo-scaled.png\",\"width\":2560,\"height\":1711},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/produkt\\\/channel-slalom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/heim\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Channel Slalom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/\",\"name\":\"Animal Products\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#organization\",\"name\":\"Animal Products\",\"url\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/animalproducts.nl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/AnimalProducts-logo-v2-liggend-def-scaled.png\",\"contentUrl\":\"https:\\\/\\\/animalproducts.nl\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/AnimalProducts-logo-v2-liggend-def-scaled.png\",\"width\":2560,\"height\":1266,\"caption\":\"Animal Products\"},\"image\":{\"@id\":\"https:\\\/\\\/animalproducts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Channel Slalom - Animal Products","description":"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/","og_locale":"de_DE","og_type":"article","og_title":"Channel Slalom - Animal Products","og_description":"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.","og_url":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/","og_site_name":"Animal Products","og_image":[{"width":2560,"height":1711,"url":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/11\/Slalom-Pasillo-scaled.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/","url":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/","name":"Channel Slalom - Animal Products","isPartOf":{"@id":"https:\/\/animalproducts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/#primaryimage"},"image":{"@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/#primaryimage"},"thumbnailUrl":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/11\/Slalom-Pasillo-scaled.png","datePublished":"2025-11-06T12:53:07+00:00","description":"Der Gassenslalom besteht aus 12 Stangen, von denen 6 beweglich sind und so einen Kanal (Gasse) bilden k\u00f6nnen. Die beweglichen Stangen werden auf verschiebbaren Modulen befestigt, die wiederum an den seitlichen Streben montiert werden \u2013 abwechselnd zu den festen Stangen.","breadcrumb":{"@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/#primaryimage","url":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/11\/Slalom-Pasillo-scaled.png","contentUrl":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/11\/Slalom-Pasillo-scaled.png","width":2560,"height":1711},{"@type":"BreadcrumbList","@id":"https:\/\/animalproducts.nl\/de\/produkt\/channel-slalom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Shop","item":"https:\/\/animalproducts.nl\/de\/heim\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/animalproducts.nl\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Channel Slalom"}]},{"@type":"WebSite","@id":"https:\/\/animalproducts.nl\/de\/#website","url":"https:\/\/animalproducts.nl\/de\/","name":"Animal Products","description":"","publisher":{"@id":"https:\/\/animalproducts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/animalproducts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/animalproducts.nl\/de\/#organization","name":"Animal Products","url":"https:\/\/animalproducts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/animalproducts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/07\/AnimalProducts-logo-v2-liggend-def-scaled.png","contentUrl":"https:\/\/animalproducts.nl\/wp-content\/uploads\/2025\/07\/AnimalProducts-logo-v2-liggend-def-scaled.png","width":2560,"height":1266,"caption":"Animal Products"},"image":{"@id":"https:\/\/animalproducts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/product\/31117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/comments?post=31117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/media\/29717"}],"wp:attachment":[{"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/media?parent=31117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/product_brand?post=31117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/product_cat?post=31117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/animalproducts.nl\/de\/wp-json\/wp\/v2\/product_tag?post=31117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}